{"id":4858,"date":"2018-10-02T22:11:31","date_gmt":"2018-10-02T20:11:31","guid":{"rendered":"https:\/\/www.tts-freunde.de\/blog\/?p=4858"},"modified":"2018-10-02T22:11:31","modified_gmt":"2018-10-02T20:11:31","slug":"ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2","status":"publish","type":"post","link":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/","title":{"rendered":"Ausnahme-Sportler unter den kompakten SUV: der neue Audi SQ2"},"content":{"rendered":"<div class=\"page-row\">\n<div id=\"item-916a4ec8-b726-4424-dcfa-b7629ee083a8\" class=\"page-item--topic-list\">\n<div class=\"topic-list\">\n<ul>\n<li>Neues S-Modell mit 221 kW (300 PS) Leistung, 0 \u2013 100 km\/h in 4,8 Sekunden<\/li>\n<li>Markantes Exterieurdesign, viele sportliche Akzente im Innenraum<\/li>\n<li>Karosserie um 20 Millimeter tiefergelegt, 18- und 19-Zoll-Ra\u0308der<\/li>\n<\/ul>\n<div class=\"page-row\">\n<div class=\"container\">\n<div id=\"item-bb63ca87-1f16-4167-a659-3cf863b0d546\" class=\"page-item--intro\">\n<div class=\"intro-text\">\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/UhF9CFV_jqE\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Markantes Design trifft gro\u00dfen Fahrspa\u00df: Im Rahmen der Paris Motor Show 2018 pra\u0308sentiert Audi erstmals den SQ2. Das neue Topmodell der Q2-Familie nimmt im Segment der kompakten SUV eine Ausnahmestellung ein: Es leistet 221 kW (300 PS), genug fu\u0308r einen Sprint von 0 auf 100 km\/h in 4,8 Sekunden und 250 km\/h Ho\u0308chstgeschwindigkeit. Mit dem Allradantrieb quattro und dem S-Sportfahrwerk kommt die Kraft souvera\u0308n auf die Stra\u00dfe. Bei Bedienung, Infotainment und Assistenzsystemen fa\u0308hrt der Audi SQ2 ebenfalls an der Spitze seiner Klasse.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page-row-spacer -intro\"><\/div>\n<div class=\"page-row\">\n<div class=\"container\">\n<div id=\"item-d95a6e44-20fe-4693-f432-036cbf695957\" class=\"page-item--text\">\n<div class=\"style-links-for-body-text\">\n<h3>0 \u2013 100 km\/h in 4,8 Sekunden: der Motor<\/h3>\n<p>Das Herz eines Audi S-Modells ist der Motor \u2013 im SQ2 pra\u0308sentiert sich der 2.0 TFSI in Topform. Er leistet 221 kW (300 PS) und stemmt im weiten Bereich zwischen 2.000 und 5.200 Umdrehungen pro Minute konstant 400 Nm Drehmoment. Damit u\u0308bertrifft das von Audi- Ingenieuren entwickelte und in Gyo\u030br gebaute Aggregat alle Rivalen im Segment. Das Gleiche gilt fu\u0308r die Fahrleistungen des Sport-SUV: Der Sprint von 0 auf 100 km\/h dauert 4,8 Sekunden, die Spitze ist auf 250 km\/h begrenzt.<\/p>\n<p>Der Vierzylinder-TFSI im Audi SQ2 ist ein Hochleistungsmotor, der seine Kraft aus 1.984 cm3 Hubraum scho\u0308pft. Er reagiert spontan, bis zur Drehzahlgrenze bei 6.500 Umdrehungen pro Minute. Im Modus dynamic des Fahrdynamiksystems Audi drive select spricht er noch bissiger an. Kurze Zwischengassto\u0308\u00dfe begleiten die Gangwechsel der S tronic. Gerade bei dynamischem Betrieb entwickelt der Motor einen besonders sonoren Sound. Der 2,0-Liter-TFSI-Motor wiegt nur rund 150 Kilogramm \u2013 davon profitiert neben dem Gesamtgewicht des Audi SQ2 auch die Verteilung der Achslasten.<\/p>\n<p>Zahlreiche Hightech-Features scha\u0308rfen das Profil des starken Vierzylinders. Um Fu\u0308llung und Gaswechsel zu optimieren, lassen sich Ein- und Auslassnockenwelle verstellen. Auf der Auslassseite schaltet das Audi valvelift system (AVS) den Hub der Ventile je nach Bedarf in\u00a0zwei Stufen um. Damit verringert es die Spu\u0308lverluste im Brennraum und ermo\u0308glicht speziell im unteren Drehzahlbereich die optimale Anstro\u0308mung des Turboladers mit Abgas. Die Vorteile sind ein agiles Ansprechverhalten und ein weiter gesteigertes Drehmoment. Gesteuert durch ein schnell und exakt arbeitendes elektrisches U\u0308berdruckventil, baut der Turbolader seinen Ladedruck von maximal 1,4 bar (relativ) sehr dynamisch auf. Diese Motorsteuerung steigert\u00a0die Effizienz und reduziert gerade im Teillastbetrieb den Verbrauch.<\/p>\n<p>Gro\u00dfes Augenmerk gilt beim 2.0 TFSI auch der Effizienz. Zwei elektrisch angetriebene Drehschieber, in einem Modul zusammengefasst, steuern die Ku\u0308hlwasserstro\u0308me. Ein weiterer gro\u00dfer Baustein des Thermomanagements ist der in den Zylinderkopf integrierte Abgaskru\u0308mmer. Er tra\u0308gt stark zum raschen Warmlauf bei.<\/p>\n<p>Gezielte Ma\u00dfnahmen an vielen Bauteilen steigern die Festigkeit und senken die innere Reibung. Die geregelte O\u0308lpumpe braucht wenig Antriebsenergie. Im Teillastbereich blendet das Motormanagement die Benzindirekteinspritzung FSI aus. Stattdessen erfolgt eine indirekte Einspritzung in den Ansaugtrakt, die die Partikelemissionen senkt. Daru\u0308ber hinaus reinigt ein Partikelfilter das Abgas.<\/p>\n<h3>Traktion, Stabilita\u0308t und Dynamik: die Kraftu\u0308bertragung<\/h3>\n<p><a href=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4857\" data-permalink=\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/audi-sq2-5\/\" data-orig-file=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg\" data-orig-size=\"2400,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Audi SQ2\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-300x169.jpg\" data-large-file=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-1024x576.jpg\" tabindex=\"0\" role=\"button\" class=\"alignleft size-medium wp-image-4857\" src=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-300x169.jpg 300w, https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-768x432.jpg 768w, https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-1024x576.jpg 1024w, https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-50x28.jpg 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Die Kra\u0308fte des 2.0 TFSI u\u0308bertra\u0308gt eine Siebengang S tronic, die zwischen dem ersten und dem letzten Gang eine hohe Spreizung von 8,7 aufweist. Der Fahrer kann das blitzschnell schaltende Doppelkupplungsgetriebe in den automatischen Modi D oder S betreiben oder selbst steuern. Wenn das Fahrdynamiksystem Audi drive select im \u201eefficiency\u201c-Modus arbeitet, o\u0308ffnet die Kupplung im Schubbetrieb, und der kompakte Sport-SUV rollt im Freilauf. Im Start-Stopp- Betrieb wird der Motor bei 7 km\/h Restgeschwindigkeit deaktiviert.<\/p>\n<p>Die beiden Kupplungen der Siebengang S tronic laufen im O\u0308lbad, eine kleine Zahnradpumpe mit mechanischem Antrieb versorgt sie mit O\u0308l. Bei erho\u0308htem Bedarf schaltet sich eine zweite, elektrisch angetriebene Pumpe zu. Diese effiziente O\u0308lversorgung und die geringe Reibung der einzelnen Bauteile fu\u0308hren zu einem hohen Wirkungsgrad.<\/p>\n<p>Wie bei jedem S-Modell von Audi ist der Allradantrieb quattro beim SQ2 Standard \u2013 er vereint starke Traktion mit faszinierender Dynamik. Als zentraler Baustein dient eine hydraulisch beta\u0308tigte Lamellenkupplung. Sie verteilt die Momente kontinuierlich zwischen den Achsen. Wenn die vorderen Ra\u0308der Grip verlieren, kann die Lamellenkupplung binnen weniger Millisekunden bis zu 100 Prozent der Kra\u0308fte nach hinten leiten.<\/p>\n<p>Die elektronische Regelung des quattro-Antriebs sorgt fu\u0308r Fahrspa\u00df und Fahrsicherheit auf Top-Niveau. Bereits wenn der Fahrer bei sportlicher Fahrweise einlenkt, kann sie einen Teil der Antriebsmomente auf die Hinterachse leiten \u2013 beim Gasgeben dru\u0308cken sie den schnellen SUV fo\u0308rmlich in die Kurve hinein. Beim Lastwechsel erlaubt das quattro-Management ein gezieltes Eindrehen, und beim Drift auf einer Fahrbahn mit niedrigem Reibwert gewa\u0308hrt es maximale Kontrolle und Verla\u0308sslichkeit. Bei schneller Fahrweise arbeitet der quattro-Antrieb eng mit der radselektiven Momentensteuerung zusammen, die das Handling durch winzige Bremseingriffe an den entlasteten kurveninneren Ra\u0308dern abrundet.<\/p>\n<h3>Tieferlegung um 20 Millimeter: das S-Sportfahrwerk<\/h3>\n<p>Das S-Sportfahrwerk des Audi SQ2 harmoniert optimal mit dem dynamischen Antrieb. Sportlicher abgestimmt als bei der technischen Ausgangsbasis, legt es die Karosserie um 20 Millimeter tiefer. Die Servounterstu\u0308tzung der serienma\u0308\u00dfigen Progressivlenkung hat eine S-spezifischen Kennlinie. Ihre Zahnstange ist speziell verzahnt, sodass sich die U\u0308bersetzung mit zunehmendem Lenkeinschlag a\u0308ndert \u2013 je gro\u0308\u00dfer der Lenkwinkel, desto direkter wird sie. Das steigert die Agilita\u0308t beim Rangieren, im Stadtverkehr und in engen Kurven.<\/p>\n<h3>Typisch S-Modell: das Au\u00dfendesign<\/h3>\n<p><a href=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-32.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4856\" data-permalink=\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/audi-sq2-32\/\" data-orig-file=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-32.jpg\" data-orig-size=\"2400,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Audi SQ2 32\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-32-300x169.jpg\" data-large-file=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-32-1024x576.jpg\" tabindex=\"0\" role=\"button\" class=\"alignleft size-medium wp-image-4856\" src=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-32-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-32-300x169.jpg 300w, https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-32-768x432.jpg 768w, https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-32-1024x576.jpg 1024w, https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-32-50x28.jpg 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Schon der Audi Q2 ist ein SUV mit Ecken und Kanten \u2013 die keilfo\u0308rmige Architektur und die pra\u0308zise Linienfu\u0308hrung, die flach gestaltete Kabine, der polygonale Einschnitt an der Flanke und das Blade auf der C-Sa\u0308ule verleihen ihm einen unverwechselbaren Aufritt. Beim S-Modell hat Audi das Exterieurdesign weiter gescha\u0308rft \u2013 schon die Front zeigt seine Ausnahmestellung an. Acht aufrecht stehende Doppelstege gliedern den gro\u00dfen, in Oktagonform gehaltenen Singleframe-Grill, ein Frontsplitter verbindet die a\u0308u\u00dfersten Kanten der beiden dominanten Lufteinla\u0308sse und unterstreicht so die volle Breite der bulligen SQ2-Front. Die serienma\u0308\u00dfigen LED-Scheinwerfer sowie die LED-Heckleuchten mit dynamischem Blinklicht strahlen eine charakteristische, pfeilfo\u0308rmige Lichtsignatur ab.<\/p>\n<p>Auch an den Flanken und am Heck setzen markante Details Akzente. Die Aufsatzleisten im unteren Bereich der Tu\u0308ren sind stark konturiert, das Geha\u0308use der Au\u00dfenspiegel gla\u0308nzen in Aluminiumoptik. Ein langer Dachkantenspoiler sorgt fu\u0308r ausreichend Abtrieb, der Diffusor- einsatz beinhaltet vier Abgas-Endrohre. Der Lackfa\u0308cher entha\u0308lt den serienma\u0308\u00dfigen Farbton Ibiswei\u00df sowie die Optionsfarben Vegasgelb, Arablau, Daytonagrau, Florettsilber, Gletscherwei\u00df, Korallenorange, Mythosschwarz, Quantumgrau und Tangorot.<\/p>\n<p>Alternativ zum Serien-Exterieur stellt Audi fu\u0308r den SQ2 zwei Pakete zur Wahl. Im Optikpaket schwarz sind der Singleframe, die Gitter der Lufteinla\u0308sse und der Diffusor in gla\u0308nzendem Schwarz lackiert. Das SQ2-Exterieurpaket bezieht auch die Spiegelgeha\u0308use, das Blade auf der C-Sa\u0308ule und die Endrohr-Blenden in die schwarze Optik ein. Der Dachkantenspoiler hat eine spezielle Kontur, an den Tu\u0308ren sind quattro-Schriftzu\u0308ge aufgebracht.<\/p>\n<p>Der Audi SQ2 gleitet leicht durch den Wind \u2013 sein cw-Wert betra\u0308gt 0,34. Das Gera\u0308uschniveau an Bord bleibt dank der schwingungsoptimierten Karosserie und der hohen Kompetenz von Audi bei der Aeroakustik niedrig. Ein Verbund warmumgeformter Sta\u0308hle, die extreme Festigkeit mit geringem Gewicht vereinbaren, bildet das starke Ru\u0308ckgrat der Passagierzelle und verleiht der ganzen Karosserie hohe Steifigkeit.<\/p>\n<p>Das serienma\u0308\u00dfige Fahrdynamiksystem Audi drive select la\u0308sst dem Fahrer die Wahl zwischen den Profilen auto, comfort, dynamic, efficiency und individual. U\u0308ber diese managt es den Charakter der Lenkung, der Siebengang S tronic und weiterer Systeme. U\u0308ber eine Taste kann der Fahrer zudem die Elektronische Stabilisierungskontrolle (ESC) in einen Offroad-Modus versetzen oder ganz abschalten. Ein Anfahrassistent ist auf Wunsch erha\u0308ltlich.<\/p>\n<p>Im Ra\u0308derprogramm von Audi und Audi Sport stehen zehn Designs und Gro\u0308\u00dfen zur Wahl. 18-Zoll-Leichtmetallra\u0308der mit Reifen im Format 235\/45 sind Serie, auf Wunsch gibt es 19-Zo\u0308ller mit Reifen im Format 235\/40 (Serie beim SQ2-Exterieurpaket). Die gro\u00df dimensionierten Radbremsen messen 340 Millimeter Durchmesser vorne und 310 Millimeter hinten. Sie sind besonders standfest und ihre Sa\u0308ttel \u2013 optional rot statt schwarz lackiert \u2013 tragen S-Badges.<\/p>\n<h3>Dynamische Akzente: der Innenraum<\/h3>\n<p><a href=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-23.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4855\" data-permalink=\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/audi-sq2-23\/\" data-orig-file=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-23.jpg\" data-orig-size=\"2400,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Audi SQ2 23\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-23-300x169.jpg\" data-large-file=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-23-1024x576.jpg\" tabindex=\"0\" role=\"button\" class=\"alignleft size-medium wp-image-4855\" src=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-23-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-23-300x169.jpg 300w, https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-23-768x432.jpg 768w, https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-23-1024x576.jpg 1024w, https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-23-50x28.jpg 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Der kompakte Audi SQ2, weist 4.210 Millimeter Au\u00dfenla\u0308nge auf und hat einen Radstand von 2.594 Millimeter \u2013 dadurch bietet sein Innenraum reichlich Platz. Das Gepa\u0308ckabteil ha\u0308lt je nach Stellung der zweifach oder dreifach geteilten Fondlehnen 355 bis 1.000 Liter Volumen bereit. Zur Serienausstattung geho\u0308ren Sportsitze, eine Mittelarmlehne vorn, eine Klimaautomatik,\u00a0ein Sport-Multifunktionslenkrad \u2013 optional mit Wippen fu\u0308r die S tronic \u2013 sowie das Fahrer- informationssystem (FIS) mit Farbdisplay.<\/p>\n<p>Anstelle des FIS kommt optional das Audi virtual cockpit an Bord \u2013 der Fahrer steuert das volldigitale Kombiinstrument u\u0308ber die Lenkradtasten. Sein 12,3 Zoll-Bildschirm bietet drei unterschiedliche Ansichten, darunter einen Screen, der den Drehzahlmesser in den Mittelpunkt ru\u0308ckt. Die wichtigsten Informationen sind zudem auf einem Head-up-Display zu sehen, einer weiteren Option.<\/p>\n<p>Das Interieurdesign fu\u0308hrt die progressive, straffe Linienfu\u0308hrung des Exterieurs fort und bietet sportliche Akzente bei Farben und Materialien. Der Dachhimmel, die Sa\u0308ulen und die Sitzbezu\u0308ge sind serienma\u0308\u00dfig in Schwarz gehalten, die Dekorleiste an der Instrumententafel besteht aus matt gebu\u0308rstetem Aluminium. Die Pedalkappen sowie die Fu\u00dfstu\u0308tze sind aus Edelstahl gefertigt, die beleuchteten Einstiegsleisten vorn tragen S-Logos. Die Instrumenten-Zifferbla\u0308tter sind grau und die Zeiger wei\u00df gefa\u0308rbt. Beim Einschalten der Zu\u0308ndung erscheinen auf dem MMI-Monitor und dem Display im Kombiinstrument, beziehungsweise im Audi virtual cockpit, S-spezifische Start-Screens.<\/p>\n<p>Serienma\u0308\u00dfig sind die Sitze des Audi SQ2 mit einer Kombination aus Leder und Stoff bezogen. Auf Wunsch gibt es einen Leder-\/Alcantara-Mix sowie Leder Feinnappa. Akzentstreifen, Kontrastna\u0308hte in Rot und Grau sowie S-Pra\u0308gungen komplettieren das Angebot. Die Leder Feinnappa-Bezu\u0308ge sind alternativ zur Ausfu\u0308hrung in Schwarz auch zweifarbig in Schwarz mit Rot und mit Rautensteppung erha\u0308ltlich. Bei der Dekorleiste existieren zwei Options-Varianten: roter Eloxallack und die beleuchtete Ausfu\u0308hrung \u201eLichtgrafik Format\u201c (mit dem zehnfarbigen Ambiente-Lichtpaket). Weitere Wunschausstattungen sind die Luftdu\u0308sen mit roten Innenringen und das unten abgeflachte Lenkrad mit Schaltwippen.<\/p>\n<p>Das SQ2-Interieurpaket fasst drei dieser Features zusammen \u2013 die Ausstro\u0308mer mit roten Ringen, die zweifarbigen Leder Feinnappa-Sitze und das Ambiente-Lichtpaket samt beleuchteter Dekor- leiste. Dazu gibt es spezifische Fu\u00dfmatten und eine Schlu\u0308sselblende jeweils mit SQ2-Schriftzug.<\/p>\n<h3>Top-Vernetzung: die MMI Navigation plus und Audi connect<\/h3>\n<p><a href=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4854\" data-permalink=\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/audi-sq2-1-3\/\" data-orig-file=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-1.jpg\" data-orig-size=\"2400,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Audi SQ2 1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-1-300x169.jpg\" data-large-file=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-1-1024x576.jpg\" tabindex=\"0\" role=\"button\" class=\"alignleft size-medium wp-image-4854\" src=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-1-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-1-300x169.jpg 300w, https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-1-768x432.jpg 768w, https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-1-1024x576.jpg 1024w, https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2-1-50x28.jpg 50w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Wie im Audi Q2 ist auch im SQ2 die Infotainment-Palette als breite Matrix konzipiert. An der Spitze steht die MMI Navigation plus mit MMI touch. Ihre Menu\u0308struktur ist klar aufgebaut, der Dreh-\/Dru\u0308cksteller auf der Konsole des Mitteltunnels integriert ein Touchpad, das auch Mehrfinger-Scrollen und Zoomen ermo\u0308glicht. Die Sprachsteuerung und die MMI-Suche laufen ebenfalls schnell und sicher ab: In der Regel genu\u0308gt die Eingabe weniger Zeichen oder Worte, um zum gewu\u0308nschten Ziel zu gelangen. Das Display der MMI Navigation plus misst 8,3 Zoll, das Datenu\u0308bertragungsmodul unterstu\u0308tzt den schnellen Mobilfunkstandard LTE und integriert einen WLAN-Hotspot fu\u0308r die mobilen Gera\u0308te der Passagiere.<\/p>\n<p>Zur MMI Navigation plus geho\u0308rt auch das Paket Audi connect (Option bei der MMI Navigation). Eine fest im Auto integrierte SIM-Karte, die Audi connect SIM, holt zahlreiche Online-Services an Bord, darunter die Verkehrsinformationen online, die Navigation mit Google Earth, Reise- und Parkplatzinformationen sowie den Zugang zu Twitter und zum E-Mail-Postfach. Die kostenlose myAudi App verbindet das Smartphone des Besitzers mit dem Auto. Sie ermo\u0308glicht Funktionen wie das Online Media Streaming und die U\u0308bertragung des Kalenders ins MMI.<\/p>\n<p>Zum Infotainment-Angebot im Audi SQ2 geho\u0308ren Bausteine wie das Audi smartphone interface. Es bindet iOS- und Android-Handys mit ihren Umgebungen Apple CarPlay oder Android Auto in das MMI-System ein. Das Bang &amp; Olufsen Sound System steuert 14 Lautsprecher u\u0308ber einen Versta\u0308rker mit 705 Watt Leistung an. Spangen aus eloxiertem Aluminium fassen die Tiefto\u0308ner ein. LED-Lichtleiter strahlen wei\u00dfes Licht ab.<\/p>\n<h3>Technologien aus der Oberklasse: die Fahrerassistenzsysteme<\/h3>\n<p>Die Fahrerassistenzsysteme fu\u0308r den Audi SQ2 stammen aus der Oberklasse. Audi pre sense front ist serienma\u0308\u00dfig an Bord und kann gefa\u0308hrliche Situationen, die mit querenden Fu\u00dfga\u0308ngern oder anderen Fahrzeugen vor dem Auto entstehen, per Radar erkennen. Das System warnt den Fahrer akustisch und optisch und leitet gegebenenfalls eine Vollbremsung ein. Eine Kollision kann so unter Umsta\u0308nden verhindert oder deren Schwere gemindert werden.<\/p>\n<p>Die beliebtesten optionalen Systeme sind im Assistenz-Paket zusammengefasst, darunter die adaptive cruise control mit Stop &amp; Go-Funktion und der Stauassistent, der neben dem Radar- sensor auch die Frontkamera nutzt. Er kann im za\u0308hflie\u00dfenden Verkehr auf gut ausgebauten Stra\u00dfen bis 65 km\/h beim Lenken, Beschleunigen und Bremsen unterstu\u0308tzen.<\/p>\n<p>Der Audi active lane assist hilft dem Fahrer beim Halten der Spur. Der optionale Parkassistent kann den kompakten Sport-SUV in La\u0308ngs- und Querparklu\u0308cken steuern. Will der Fahrer wieder ru\u0308ckwa\u0308rts aus der Querparklu\u0308cke setzen, kommt der Querverkehrassistent hinten zum Einsatz. Eine weitere Assistenzfunktion ist der Audi side assist. Er warnt den Fahrer durch eine Anzeige am jeweiligen Au\u00dfenspiegel vor einer mo\u0308glichen Gefahr beim Spurwechsel per Radar.<\/p>\n<p>Der neue Audi SQ2 wird Anfang Oktober erstmals im Rahmen der Paris Motor Show 2018 pra\u0308sentiert.<\/p>\n<p>[instagram-feed]<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Neues S-Modell mit 221 kW (300 PS) Leistung, 0 \u2013 100 km\/h in 4,8 Sekunden Markantes Exterieurdesign, viele sportliche Akzente im Innenraum Karosserie um 20 Millimeter tiefergelegt, 18- und 19-Zoll-Ra\u0308der Markantes Design trifft gro\u00dfen Fahrspa\u00df: Im Rahmen der Paris Motor Show 2018 pra\u0308sentiert Audi erstmals den SQ2. Das neue Topmodell [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4857,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Ausnahme-Sportler unter den kompakten SUV: der neue #Audi #SQ2","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[13],"tags":[20,222],"class_list":["post-4858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-q3-q5-q7","tag-audi","tag-sq2"],"wppr_data":{"cwp_meta_box_check":"No"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ausnahme-Sportler unter den kompakten SUV: der neue Audi SQ2 - Audi Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ausnahme-Sportler unter den kompakten SUV: der neue Audi SQ2 - Audi Blog\" \/>\n<meta property=\"og:description\" content=\"Neues S-Modell mit 221 kW (300 PS) Leistung, 0 \u2013 100 km\/h in 4,8 Sekunden Markantes Exterieurdesign, viele sportliche Akzente im Innenraum Karosserie um 20 Millimeter tiefergelegt, 18- und 19-Zoll-Ra\u0308der Markantes Design trifft gro\u00dfen Fahrspa\u00df: Im Rahmen der Paris Motor Show 2018 pra\u0308sentiert Audi erstmals den SQ2. Das neue Topmodell [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/\" \/>\n<meta property=\"og:site_name\" content=\"Audi Blog\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-02T20:11:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/#\/schema\/person\/b67f6a54e98f013bd281dbe05514b701\"},\"headline\":\"Ausnahme-Sportler unter den kompakten SUV: der neue Audi SQ2\",\"datePublished\":\"2018-10-02T20:11:31+00:00\",\"dateModified\":\"2018-10-02T20:11:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/\"},\"wordCount\":2115,\"publisher\":{\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg\",\"keywords\":[\"audi\",\"sq2\"],\"articleSection\":[\"Q2 - Q3 - Q5 - Q6 - Q7 - Q8 - Q9\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/\",\"url\":\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/\",\"name\":\"Ausnahme-Sportler unter den kompakten SUV: der neue Audi SQ2 - Audi Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg\",\"datePublished\":\"2018-10-02T20:11:31+00:00\",\"dateModified\":\"2018-10-02T20:11:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#primaryimage\",\"url\":\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg\",\"contentUrl\":\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg\",\"width\":2400,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tts-freunde.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausnahme-Sportler unter den kompakten SUV: der neue Audi SQ2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/#website\",\"url\":\"https:\/\/www.tts-freunde.de\/blog\/\",\"name\":\"Audi Blog\",\"description\":\"Deutscher Audi Blog - TTS-Freunde\",\"publisher\":{\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tts-freunde.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/#organization\",\"name\":\"Audi Blog\",\"url\":\"https:\/\/www.tts-freunde.de\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2022\/12\/logo_2022.jpg\",\"contentUrl\":\"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2022\/12\/logo_2022.jpg\",\"width\":240,\"height\":41,\"caption\":\"Audi Blog\"},\"image\":{\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/#\/schema\/person\/b67f6a54e98f013bd281dbe05514b701\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.tts-freunde.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/08a4bd330e25056ddb430c28136b38a6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/08a4bd330e25056ddb430c28136b38a6?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\/\/www.tts-freunde.de\"],\"url\":\"https:\/\/www.tts-freunde.de\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ausnahme-Sportler unter den kompakten SUV: der neue Audi SQ2 - Audi Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/","og_locale":"de_DE","og_type":"article","og_title":"Ausnahme-Sportler unter den kompakten SUV: der neue Audi SQ2 - Audi Blog","og_description":"Neues S-Modell mit 221 kW (300 PS) Leistung, 0 \u2013 100 km\/h in 4,8 Sekunden Markantes Exterieurdesign, viele sportliche Akzente im Innenraum Karosserie um 20 Millimeter tiefergelegt, 18- und 19-Zoll-Ra\u0308der Markantes Design trifft gro\u00dfen Fahrspa\u00df: Im Rahmen der Paris Motor Show 2018 pra\u0308sentiert Audi erstmals den SQ2. Das neue Topmodell [&hellip;]","og_url":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/","og_site_name":"Audi Blog","article_published_time":"2018-10-02T20:11:31+00:00","og_image":[{"width":2400,"height":1350,"url":"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#article","isPartOf":{"@id":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/"},"author":{"name":"admin","@id":"https:\/\/www.tts-freunde.de\/blog\/#\/schema\/person\/b67f6a54e98f013bd281dbe05514b701"},"headline":"Ausnahme-Sportler unter den kompakten SUV: der neue Audi SQ2","datePublished":"2018-10-02T20:11:31+00:00","dateModified":"2018-10-02T20:11:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/"},"wordCount":2115,"publisher":{"@id":"https:\/\/www.tts-freunde.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg","keywords":["audi","sq2"],"articleSection":["Q2 - Q3 - Q5 - Q6 - Q7 - Q8 - Q9"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/","url":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/","name":"Ausnahme-Sportler unter den kompakten SUV: der neue Audi SQ2 - Audi Blog","isPartOf":{"@id":"https:\/\/www.tts-freunde.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#primaryimage"},"image":{"@id":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg","datePublished":"2018-10-02T20:11:31+00:00","dateModified":"2018-10-02T20:11:31+00:00","breadcrumb":{"@id":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#primaryimage","url":"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg","contentUrl":"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg","width":2400,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/www.tts-freunde.de\/blog\/2018\/10\/02\/ausnahme-sportler-unter-den-kompakten-suv-der-neue-audi-sq2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tts-freunde.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Ausnahme-Sportler unter den kompakten SUV: der neue Audi SQ2"}]},{"@type":"WebSite","@id":"https:\/\/www.tts-freunde.de\/blog\/#website","url":"https:\/\/www.tts-freunde.de\/blog\/","name":"Audi Blog","description":"Deutscher Audi Blog - TTS-Freunde","publisher":{"@id":"https:\/\/www.tts-freunde.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tts-freunde.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.tts-freunde.de\/blog\/#organization","name":"Audi Blog","url":"https:\/\/www.tts-freunde.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.tts-freunde.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2022\/12\/logo_2022.jpg","contentUrl":"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2022\/12\/logo_2022.jpg","width":240,"height":41,"caption":"Audi Blog"},"image":{"@id":"https:\/\/www.tts-freunde.de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.tts-freunde.de\/blog\/#\/schema\/person\/b67f6a54e98f013bd281dbe05514b701","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.tts-freunde.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/08a4bd330e25056ddb430c28136b38a6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08a4bd330e25056ddb430c28136b38a6?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.tts-freunde.de"],"url":"https:\/\/www.tts-freunde.de\/blog\/author\/admin\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.tts-freunde.de\/blog\/wp-content\/uploads\/2018\/10\/Audi-SQ2.jpg","jetpack_shortlink":"https:\/\/wp.me\/p67hWW-1gm","jetpack_likes_enabled":false,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.tts-freunde.de\/blog\/wp-json\/wp\/v2\/posts\/4858"}],"collection":[{"href":"https:\/\/www.tts-freunde.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tts-freunde.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tts-freunde.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tts-freunde.de\/blog\/wp-json\/wp\/v2\/comments?post=4858"}],"version-history":[{"count":4,"href":"https:\/\/www.tts-freunde.de\/blog\/wp-json\/wp\/v2\/posts\/4858\/revisions"}],"predecessor-version":[{"id":4862,"href":"https:\/\/www.tts-freunde.de\/blog\/wp-json\/wp\/v2\/posts\/4858\/revisions\/4862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tts-freunde.de\/blog\/wp-json\/wp\/v2\/media\/4857"}],"wp:attachment":[{"href":"https:\/\/www.tts-freunde.de\/blog\/wp-json\/wp\/v2\/media?parent=4858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tts-freunde.de\/blog\/wp-json\/wp\/v2\/categories?post=4858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tts-freunde.de\/blog\/wp-json\/wp\/v2\/tags?post=4858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}